{"id":856,"date":"2023-10-10T15:43:11","date_gmt":"2023-10-10T13:43:11","guid":{"rendered":"https:\/\/closdeslavandes.fr\/?page_id=856"},"modified":"2023-11-30T20:39:06","modified_gmt":"2023-11-30T19:39:06","slug":"la-methode-montessori","status":"publish","type":"page","link":"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/","title":{"rendered":"LA M\u00c9THODE MONTESSORI"},"content":{"rendered":"<div class=\"lpb-clear-section\"><\/div><!-- .lpb-clear-section -->\n\n<div class=\"lpb-page-row\"><!-- .lpb-page-row -->\n<div class=\"lpb-container\"><!-- .lpb-container -->\n<div class=\"lpb-row\"><!-- .lpb-row -->\n\n<div class=\"lpb-col-12 lpb-page-item has-bg\" ><!-- .lpb-page-item -->\n\n<hr class=\"lpb-item-line\">\n<\/div><!-- \/.lpb-page-item -->\n\n<\/div><!-- \/.lpb-row -->\n<\/div><!-- \/.lpb-container -->\n<\/div><!-- \/.lpb-page-row -->\n\n<div class=\"lpb-page-row\"><!-- .lpb-page-row -->\n<div class=\"lpb-container\"><!-- .lpb-container -->\n<div class=\"lpb-row\"><!-- .lpb-row -->\n\n<div class=\"lpb-col-12 lpb-page-item has-bg\" ><!-- .lpb-page-item -->\n\n<div class=\"lpb-item-column\" >\n\t<div class=\"lpb-item-content\"><div style=\"text-align: center\">\n<h5>Initialement con\u00e7ue pour les enfants, la m\u00e9thode Montessori a \u00e9t\u00e9 adapt\u00e9e pour la rendre accessible \u00e0 un public<br \/>\nde personnes \u00e2g\u00e9es.<\/p>\n<p>Cette m\u00e9thode aide les r\u00e9sidents souffrant de troubles cognitifs \u00e0 \u00eatre plus autonomes et \u00e0 se sentir utiles au sein de l\u2019EHPAD. Elle donne des outils aux soignants pour contourner les d\u00e9faillances dues \u00e0 la vieillesse, la maladie ou le handicap.<\/p>\n<p>Elle repose sur trois valeurs cl\u00e9s qui sont le respect, la dignit\u00e9 et l\u2019\u00e9galit\u00e9.<\/h5>\n<\/div>\n<\/div>\n<\/div>\n<\/div><!-- \/.lpb-page-item -->\n<\/div><!-- \/.lpb-row -->\n<\/div><!-- \/.lpb-container -->\n<\/div><!-- \/.lpb-page-row -->\n\n","protected":false},"excerpt":{"rendered":"<p>Initialement con\u00e7ue pour les enfants, la m\u00e9thode Montessori a \u00e9t\u00e9 adapt\u00e9e pour la rendre accessible \u00e0 un public de personnes \u00e2g\u00e9es. Cette m\u00e9thode aide les r\u00e9sidents souffrant de troubles cognitifs \u00e0 \u00eatre plus autonomes et \u00e0 se sentir utiles au sein de l\u2019EHPAD. Elle donne des outils aux soignants pour contourner les d\u00e9faillances dues \u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-856","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Initialement con\u00e7ue pour les enfants, la m\u00e9thode Montessori a \u00e9t\u00e9 adapt\u00e9e pour la rendre accessible \u00e0 un public de personnes \u00e2g\u00e9es. Cette m\u00e9thode aide les r\u00e9sidents souffrant de troubles cognitifs \u00e0 \u00eatre plus autonomes et \u00e0 se sentir utiles au sein de l\u2019EHPAD. Elle donne des outils aux soignants pour contourner les d\u00e9faillances dues \u00e0\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Association Le Clos des Lavandes -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"LA M\u00c9THODE MONTESSORI - Association Le Clos des Lavandes\" \/>\n\t\t<meta property=\"og:description\" content=\"Initialement con\u00e7ue pour les enfants, la m\u00e9thode Montessori a \u00e9t\u00e9 adapt\u00e9e pour la rendre accessible \u00e0 un public de personnes \u00e2g\u00e9es. Cette m\u00e9thode aide les r\u00e9sidents souffrant de troubles cognitifs \u00e0 \u00eatre plus autonomes et \u00e0 se sentir utiles au sein de l\u2019EHPAD. Elle donne des outils aux soignants pour contourner les d\u00e9faillances dues \u00e0\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-10T13:43:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-11-30T19:39:06+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"LA M\u00c9THODE MONTESSORI - Association Le Clos des Lavandes\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Initialement con\u00e7ue pour les enfants, la m\u00e9thode Montessori a \u00e9t\u00e9 adapt\u00e9e pour la rendre accessible \u00e0 un public de personnes \u00e2g\u00e9es. Cette m\u00e9thode aide les r\u00e9sidents souffrant de troubles cognitifs \u00e0 \u00eatre plus autonomes et \u00e0 se sentir utiles au sein de l\u2019EHPAD. Elle donne des outils aux soignants pour contourner les d\u00e9faillances dues \u00e0\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/closdeslavandes.fr\\\/index.php\\\/la-methode-montessori\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/closdeslavandes.fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/closdeslavandes.fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/closdeslavandes.fr\\\/index.php\\\/la-methode-montessori\\\/#listItem\",\"name\":\"LA M\\u00c9THODE MONTESSORI\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/closdeslavandes.fr\\\/index.php\\\/la-methode-montessori\\\/#listItem\",\"position\":2,\"name\":\"LA M\\u00c9THODE MONTESSORI\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/closdeslavandes.fr#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/closdeslavandes.fr\\\/#organization\",\"name\":\"Association Le Clos des Lavandes\",\"url\":\"https:\\\/\\\/closdeslavandes.fr\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/closdeslavandes.fr\\\/index.php\\\/la-methode-montessori\\\/#webpage\",\"url\":\"https:\\\/\\\/closdeslavandes.fr\\\/index.php\\\/la-methode-montessori\\\/\",\"name\":\"LA M\\u00c9THODE MONTESSORI - Association Le Clos des Lavandes\",\"description\":\"Initialement con\\u00e7ue pour les enfants, la m\\u00e9thode Montessori a \\u00e9t\\u00e9 adapt\\u00e9e pour la rendre accessible \\u00e0 un public de personnes \\u00e2g\\u00e9es. Cette m\\u00e9thode aide les r\\u00e9sidents souffrant de troubles cognitifs \\u00e0 \\u00eatre plus autonomes et \\u00e0 se sentir utiles au sein de l\\u2019EHPAD. Elle donne des outils aux soignants pour contourner les d\\u00e9faillances dues \\u00e0\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/closdeslavandes.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/closdeslavandes.fr\\\/index.php\\\/la-methode-montessori\\\/#breadcrumblist\"},\"datePublished\":\"2023-10-10T15:43:11+02:00\",\"dateModified\":\"2023-11-30T20:39:06+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/closdeslavandes.fr\\\/#website\",\"url\":\"https:\\\/\\\/closdeslavandes.fr\\\/\",\"name\":\"Association Le Clos des Lavandes\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/closdeslavandes.fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"LA M\u00c9THODE MONTESSORI - Association Le Clos des Lavandes","description":"Initialement con\u00e7ue pour les enfants, la m\u00e9thode Montessori a \u00e9t\u00e9 adapt\u00e9e pour la rendre accessible \u00e0 un public de personnes \u00e2g\u00e9es. Cette m\u00e9thode aide les r\u00e9sidents souffrant de troubles cognitifs \u00e0 \u00eatre plus autonomes et \u00e0 se sentir utiles au sein de l\u2019EHPAD. Elle donne des outils aux soignants pour contourner les d\u00e9faillances dues \u00e0","canonical_url":"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/closdeslavandes.fr#listItem","position":1,"name":"Home","item":"https:\/\/closdeslavandes.fr","nextItem":{"@type":"ListItem","@id":"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/#listItem","name":"LA M\u00c9THODE MONTESSORI"}},{"@type":"ListItem","@id":"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/#listItem","position":2,"name":"LA M\u00c9THODE MONTESSORI","previousItem":{"@type":"ListItem","@id":"https:\/\/closdeslavandes.fr#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/closdeslavandes.fr\/#organization","name":"Association Le Clos des Lavandes","url":"https:\/\/closdeslavandes.fr\/"},{"@type":"WebPage","@id":"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/#webpage","url":"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/","name":"LA M\u00c9THODE MONTESSORI - Association Le Clos des Lavandes","description":"Initialement con\u00e7ue pour les enfants, la m\u00e9thode Montessori a \u00e9t\u00e9 adapt\u00e9e pour la rendre accessible \u00e0 un public de personnes \u00e2g\u00e9es. Cette m\u00e9thode aide les r\u00e9sidents souffrant de troubles cognitifs \u00e0 \u00eatre plus autonomes et \u00e0 se sentir utiles au sein de l\u2019EHPAD. Elle donne des outils aux soignants pour contourner les d\u00e9faillances dues \u00e0","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/closdeslavandes.fr\/#website"},"breadcrumb":{"@id":"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/#breadcrumblist"},"datePublished":"2023-10-10T15:43:11+02:00","dateModified":"2023-11-30T20:39:06+01:00"},{"@type":"WebSite","@id":"https:\/\/closdeslavandes.fr\/#website","url":"https:\/\/closdeslavandes.fr\/","name":"Association Le Clos des Lavandes","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/closdeslavandes.fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Association Le Clos des Lavandes -","og:type":"article","og:title":"LA M\u00c9THODE MONTESSORI - Association Le Clos des Lavandes","og:description":"Initialement con\u00e7ue pour les enfants, la m\u00e9thode Montessori a \u00e9t\u00e9 adapt\u00e9e pour la rendre accessible \u00e0 un public de personnes \u00e2g\u00e9es. Cette m\u00e9thode aide les r\u00e9sidents souffrant de troubles cognitifs \u00e0 \u00eatre plus autonomes et \u00e0 se sentir utiles au sein de l\u2019EHPAD. Elle donne des outils aux soignants pour contourner les d\u00e9faillances dues \u00e0","og:url":"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/","article:published_time":"2023-10-10T13:43:11+00:00","article:modified_time":"2023-11-30T19:39:06+00:00","twitter:card":"summary_large_image","twitter:title":"LA M\u00c9THODE MONTESSORI - Association Le Clos des Lavandes","twitter:description":"Initialement con\u00e7ue pour les enfants, la m\u00e9thode Montessori a \u00e9t\u00e9 adapt\u00e9e pour la rendre accessible \u00e0 un public de personnes \u00e2g\u00e9es. Cette m\u00e9thode aide les r\u00e9sidents souffrant de troubles cognitifs \u00e0 \u00eatre plus autonomes et \u00e0 se sentir utiles au sein de l\u2019EHPAD. Elle donne des outils aux soignants pour contourner les d\u00e9faillances dues \u00e0"},"aioseo_meta_data":{"post_id":"856","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-11-29 19:26:11","updated":"2026-08-12 07:31:34","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/closdeslavandes.fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLA M\u00c9THODE MONTESSORI\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/closdeslavandes.fr"},{"label":"LA M\u00c9THODE MONTESSORI","link":"https:\/\/closdeslavandes.fr\/index.php\/la-methode-montessori\/"}],"_links":{"self":[{"href":"https:\/\/closdeslavandes.fr\/index.php\/wp-json\/wp\/v2\/pages\/856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/closdeslavandes.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/closdeslavandes.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/closdeslavandes.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/closdeslavandes.fr\/index.php\/wp-json\/wp\/v2\/comments?post=856"}],"version-history":[{"count":6,"href":"https:\/\/closdeslavandes.fr\/index.php\/wp-json\/wp\/v2\/pages\/856\/revisions"}],"predecessor-version":[{"id":1167,"href":"https:\/\/closdeslavandes.fr\/index.php\/wp-json\/wp\/v2\/pages\/856\/revisions\/1167"}],"wp:attachment":[{"href":"https:\/\/closdeslavandes.fr\/index.php\/wp-json\/wp\/v2\/media?parent=856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}